{"id":30453,"date":"2019-08-19T11:04:10","date_gmt":"2019-08-19T17:04:10","guid":{"rendered":"http:\/\/www.inces.gob.ve\/?p=30453"},"modified":"2020-05-28T20:27:45","modified_gmt":"2020-05-29T00:27:45","slug":"amazonas-se-retoma-el-programa-penitenciario-en-la-region-amazonense","status":"publish","type":"post","link":"https:\/\/inces.gob.ve\/index.php\/2019\/08\/19\/amazonas-se-retoma-el-programa-penitenciario-en-la-region-amazonense\/","title":{"rendered":"AMAZONAS | Se retoma el Programa Penitenciario en la regi\u00f3n amazonense"},"content":{"rendered":"<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\"><i><b>** Inces forma a los privados de libertad<\/b><\/i><\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><!--more--><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\"><b>ALEX M\u00c9NDEZ<\/b><\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\">Desde el primero de agosto, por orientaci\u00f3n del gerente regional de Inces Amazonas, Oscar Rattia, se retom\u00f3 el Programa Penitenciario que estuvo en pausa por m\u00e1s de cuatro meses.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\">Este programa brinda la oportunidad, a los privados de libertad, de reinsertarse en la sociedad a trav\u00e9s de cursos de formaci\u00f3n productiva. El responsable asignado para llevar la tarea de formar a esta poblaci\u00f3n es el profesor Beliz Principal.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\">El profesor ofreci\u00f3 detalles de los cursos iniciados en el centro penitenciario \u201cLuisa C\u00e1ceres de Arismendi\u201d. Desde el d\u00eda lunes 29 de agosto y martes 30, se inici\u00f3 con un curso de Desarrollo y Crecimiento Personal, dirigido a los recluidos en la polic\u00eda municipal.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\">Hasta los momentos en la polic\u00eda municipal se han formado nueve privados de libertad y en el comando de la polic\u00eda estadal, se est\u00e1n formando 56 personas entre hombres y mujeres.<\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\">\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\"><b>Inclusi\u00f3n de reclusos en Educaci\u00f3n Media, modalidad J\u00f3venes Adultas y adultos<\/b><\/span><\/span><\/span><\/p>\n<p class=\"western\" align=\"justify\"><span style=\"font-family: Arial, sans-serif;\"><span style=\"font-size: x-large;\"><span lang=\"es-ES\">Beliz Principal inform\u00f3 que se est\u00e1 revisando la propuesta de incluir a los privados de libertad de la c\u00e1rcel \u201cLuisa C\u00e1ceres de Arismendi\u201d al programa de Educaci\u00f3n Media, modalidad de j\u00f3venes adultas y adultos, para que algunos recluidos logren sacar su bachillerato. Ya se inici\u00f3 la jornada de inscripci\u00f3n en la polic\u00eda municipal donde ya se tiene registrado un grupo de nueve recluidos.<\/span><\/span><\/span><\/p>\n<p class=\"western\" lang=\"es-VE\" align=\"justify\">\n<p class=\"western\" align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>** Inces forma a los privados de libertad<\/p>\n","protected":false},"author":15,"featured_media":30454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-30453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/30453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=30453"}],"version-history":[{"count":1,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/30453\/revisions"}],"predecessor-version":[{"id":30455,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/30453\/revisions\/30455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/media\/30454"}],"wp:attachment":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=30453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/categories?post=30453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/tags?post=30453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}