{"id":40366,"date":"2021-10-15T08:48:13","date_gmt":"2021-10-15T12:48:13","guid":{"rendered":"https:\/\/inces.gob.ve\/?p=40366"},"modified":"2021-10-15T08:48:34","modified_gmt":"2021-10-15T12:48:34","slug":"trujillo-inces-reparo-408-mesas-sillas-entrujillo","status":"publish","type":"post","link":"https:\/\/inces.gob.ve\/index.php\/2021\/10\/15\/trujillo-inces-reparo-408-mesas-sillas-entrujillo\/","title":{"rendered":"TRUJILLO | Inces repar\u00f3 408 mesas sillas en Trujillo"},"content":{"rendered":"<p align=\"justify\"><span style=\"font-size: 14pt;\"><em><strong>** Los planteles atendidos son: Escuela Estanislao Carrillo, 49 piezas; Escuela Nacional Bolivariana \u201cLa Llanada\u201d 36; Escuela Bolivariana \u201cRafael Quevedo Urbina\u201d, 30; Unidad Educativa \u201cMonse\u00f1or Arias Blanco\u201d 42; Unidad Educativa \u201cRafael Rangel 38; Unidad Educativa \u201cManuel Mar\u00eda Carrasquero\u201d 53; Escuela Bolivariana \u201cJulio S\u00e1nchez Vivas\u201d 26 y Escuela Bolivariana \u201cCuba\u201d 61 piezas\u00a0<\/strong><\/em><!--more--><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 14pt;\"><strong>MAR\u00cdA CABRERA<\/strong><\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 14pt;\">Un total de 408 piezas que conforman parte del mobiliario de nueve planteles de Trujillo, fueron objeto de refacci\u00f3n y acondicionamiento por parte de la brigada del Inces-Trujillo a los cuales se suma <span style=\"color: #000000;\"><span style=\"font-family: Calibri, Helvetica, sans-serif;\">la\u00a0<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, serif;\">infraestructura f\u00edsica de los planteles que tiene como responsables a las Zonas Educativas de los estados\u00a0<\/span><\/span>para el inicio de las clases del nuevo a\u00f1o escolar 2021-2022.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 14pt;\">Los planteles atendidos en esta ocasi\u00f3n fueron: Escuela Etanislao Carrillo,49 piezas; Escuela Nacional Bolivariana \u201cLa Llanada\u201d 36; Escuela Bolivariana \u201cRafael Quevedo Urbina\u201d, 30; Unidad Educativa \u201cMonse\u00f1or Arias Blanco\u201d 42; Unidad Educativa \u201cRafael Rangel 38; Unidad Educativa \u201cManuel Mar\u00eda Carrasquero\u201d 53; Escuela Bolivariana \u201cJulio S\u00e1nchez Vivas\u201d 26 y Escuela Bolivariana \u201cCuba\u201d 61 piezas respectivamente.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 14pt;\">La atenci\u00f3n de estos 9 planteles suma la totalidad de 408 piezas recuperadas de mesas sillas en un plan nacional en el que el Inces-Trujillo est\u00e1 involucrado gracias a las alianzas que desde hace unos meses este organismo efectu\u00f3 con la Zona Educativa y que arroja como resultados el descrito.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 14pt;\">Por el Inces-Trujillo estuvieron presentes Marlene Umbr\u00eda, jefe del Programa de televisi\u00f3n educativa, y los maestros t\u00e9cnicos voluntarios, Conrado Briante y Jos\u00e9 Araujo quienes conformaron la brigada que esta inserta en el plan \u201cUna\u00a0 Gota de Amor para mi Escuela\u201d que se encargar\u00e1 de la luminaria, reparaci\u00f3n de mesas sillas e infraestructura.<\/span><\/p>\n<p align=\"justify\"><span style=\"font-size: 14pt;\">Ang\u00e9lica Mor\u00f3n Aldana por el Inces y Lirosbeya Torres, de la Zona Educativa son las responsables de esta acci\u00f3n en la que la poblaci\u00f3n de los nueve planteles trujillanos son los beneficiarios directos y a <span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, serif;\">las que les practicar\u00e1 trabajos menores como: luminaria, infraestructura y las mesas sillas, que\u00a0<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, serif;\">depender\u00e1<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, serif;\">n<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, serif;\">\u00a0de\u00a0<\/span><\/span><span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, serif;\">la cuota asignada para atender en la entidad aquellas que presentan deterioro en estas \u00e1reas.<\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>** Los planteles atendidos son: Escuela Estanislao Carrillo, 49 piezas; Escuela Nacional Bolivariana \u201cLa Llanada\u201d 36; Escuela Bolivariana \u201cRafael Quevedo Urbina\u201d, 30; Unidad Educativa \u201cMonse\u00f1or Arias Blanco\u201d 42; Unidad Educativa \u201cRafael Rangel 38; Unidad Educativa \u201cManuel Mar\u00eda Carrasquero\u201d 53; Escuela Bolivariana \u201cJulio S\u00e1nchez Vivas\u201d 26 y Escuela Bolivariana \u201cCuba\u201d 61 piezas\u00a0<\/p>\n","protected":false},"author":4,"featured_media":40367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-40366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/40366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=40366"}],"version-history":[{"count":2,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/40366\/revisions"}],"predecessor-version":[{"id":40369,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/40366\/revisions\/40369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/media\/40367"}],"wp:attachment":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=40366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/categories?post=40366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/tags?post=40366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}