{"id":72272,"date":"2026-05-12T10:58:45","date_gmt":"2026-05-12T14:58:45","guid":{"rendered":"https:\/\/inces.gob.ve\/?p=72272"},"modified":"2026-05-12T16:28:04","modified_gmt":"2026-05-12T20:28:04","slug":"aragua-inces-impulsa-el-dominio-tecnico-de-la-fibra-optica-en-maracay","status":"publish","type":"post","link":"https:\/\/inces.gob.ve\/index.php\/2026\/05\/12\/aragua-inces-impulsa-el-dominio-tecnico-de-la-fibra-optica-en-maracay\/","title":{"rendered":"ARAGUA | Inces impulsa el dominio t\u00e9cnico de la Fibra \u00d3ptica en Maracay"},"content":{"rendered":"<div id=\":oj\" class=\"ii gt\">\n<div id=\":nx\" class=\"a3s aiL \">\n<div id=\"avWBGd-868\">\n<div dir=\"ltr\">\n<div class=\"gmail_quote\">\n<div dir=\"auto\">\n<div data-smartmail=\"gmail_signature\">\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<div dir=\"ltr\">\n<div>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\"><strong><em>** La instituci\u00f3n potencia la Formaci\u00f3n T\u00e9cnica Profesional en redes de alta velocidad.<\/em><\/strong><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\"><!--more--><\/span><\/p>\n<div id=\":oq\" class=\"hq gt \" style=\"text-align: justify;\"><\/div>\n<div>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\">NINOSKA PATRIZ<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\">Desde el Auditorio Sim\u00f3n Bol\u00edvar, el Inces Regi\u00f3n Aragua dio inicio a una formaci\u00f3n especializada en materia de telecomunicaciones. Esta actividad surge mediante un convenio estrat\u00e9gico con Cincatesa, buscando elevar el nivel t\u00e9cnico de los participantes en el manejo de infraestructuras cr\u00edticas. El evento reuni\u00f3 a un nutrido grupo de entusiastas y profesionales dispuestos a actualizar sus destrezas en el \u00e1rea.<\/span><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-72274 size-full\" src=\"https:\/\/inces.gob.ve\/wp-content\/uploads\/2026\/05\/1000540773-e1778597612736.jpg\" alt=\"\" width=\"800\" height=\"561\" \/><\/p>\n<div>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\">La ponencia principal estuvo a cargo del jefe del Departamento de Inform\u00e1tica, Arturo Galindo, experto en la materia. Durante el encuentro, se establecieron las bases te\u00f3ricas sobre la transmisi\u00f3n de datos, haciendo \u00e9nfasis en la importancia de contar con personal calificado para el despliegue de redes modernas. La asistencia super\u00f3 los 80 inscritos, reflejando el alto inter\u00e9s por estas tecnolog\u00edas de conectividad.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-72275 size-full aligncenter\" src=\"https:\/\/inces.gob.ve\/wp-content\/uploads\/2026\/05\/1000540769-e1778597653718.jpg\" alt=\"\" width=\"800\" height=\"493\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\">El programa acad\u00e9mico abordado cont\u00f3 con puntos cr\u00edticos como la p\u00e9rdida de se\u00f1al, detecci\u00f3n de fallas y la correcta manipulaci\u00f3n de componentes, adem\u00e1s del uso correcto de elementos mec\u00e1nicos y procedimientos de precisi\u00f3n, garantizando un servicio eficiente en el sector de las comunicaciones. Esta capacitaci\u00f3n busca dotar al estudiante de herramientas pr\u00e1cticas para resolver problemas reales en el tendido de redes.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\">La duraci\u00f3n de este ciclo formativo se estipul\u00f3 en cuatro semanas, tiempo en el cual se ejecutar\u00e1n intensas jornadas de soldaduras por fusi\u00f3n. Estas pr\u00e1cticas son esenciales para asegurar la continuidad del flujo de informaci\u00f3n a trav\u00e9s del cristal. Asimismo, el enfoque t\u00e9cnico permitir\u00e1 que los cursantes desarrollen la destreza manual necesaria para intervenir sistemas de fibra con est\u00e1ndares de calidad internacional.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-72273 size-full\" src=\"https:\/\/inces.gob.ve\/wp-content\/uploads\/2026\/05\/1000540772-e1778597724162.jpg\" alt=\"\" width=\"800\" height=\"527\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: helvetica, arial, sans-serif; font-size: 18px;\">La convocatoria estuvo dirigida a personas mayores de 18 a\u00f1os con nociones b\u00e1sicas en computaci\u00f3n o sistemas. El objetivo final es que cada integrante logre incursionar con \u00e9xito en el manejo profesional de este recurso.\u00a0<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>** La instituci\u00f3n potencia la Formaci\u00f3n T\u00e9cnica Profesional en redes de alta velocidad.<\/p>\n","protected":false},"author":15,"featured_media":72278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-72272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/72272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/comments?post=72272"}],"version-history":[{"count":2,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/72272\/revisions"}],"predecessor-version":[{"id":72280,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/posts\/72272\/revisions\/72280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/media\/72278"}],"wp:attachment":[{"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/media?parent=72272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/categories?post=72272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inces.gob.ve\/index.php\/wp-json\/wp\/v2\/tags?post=72272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}